{"id":9380,"date":"2021-03-09T21:21:44","date_gmt":"2021-03-09T20:21:44","guid":{"rendered":"https:\/\/eisbaerlin.de\/blog\/?p=9380"},"modified":"2021-03-09T21:22:58","modified_gmt":"2021-03-09T20:22:58","slug":"besonders-auswaerts-ist-es-wichtig-das-erste-tor-zu-erzielen","status":"publish","type":"post","link":"https:\/\/eisbaerlin.de\/blog\/2021\/03\/09\/besonders-auswaerts-ist-es-wichtig-das-erste-tor-zu-erzielen\/","title":{"rendered":"Kris Foucault vor dem K\u00f6ln-Spiel: &#8222;Besonders ausw\u00e4rts ist es wichtig, das erste Tor zu erzielen&#8220;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-16\" src=\"https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/2012\/09\/130px-Koelner-haie-logo_svg.png\" alt=\"\" width=\"130\" height=\"116\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-12\" src=\"https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/2012\/09\/125px-Logo_ERC_Ingolstadt_svg.png\" alt=\"\" width=\"100\" height=\"114\" \/><span style=\"color: #000000;\">Morgen Abend spielen die Eisb\u00e4ren Berlin letztmals in der diesj\u00e4hrigen Hauptrunde der PENNY DEL bei den K\u00f6lner Haien (Bully: 18:30 Uhr). Alle bisherigen drei Duelle gingen an die Hauptst\u00e4dter. W\u00e4hrend die Eisb\u00e4ren souver\u00e4n an der Tabellenspitze der Gruppe Nord thronen, k\u00e4mpfen die Domst\u00e4dter als Tabellensechster noch um die Teilnahme an den Playoffs. Macht das K\u00f6ln automatisch zu einem noch gef\u00e4hrlicheren Gegner, Headcoach Serge Aubin?<\/span><\/p>\n<blockquote><p><em><strong><span style=\"color: #ff0000;\">K\u00f6ln ist ein erfahrenes Team. Sie wissen, wie wichtig jeder einzelne Punkt zum aktuellen Zeitpunkt der Saison ist. Ich erwarte, dass sie hart aus der Kabine kommen. Wir werden weitermachen wie bisher. Mir gef\u00e4llt, wie sich das Team entwickelt. Es wird harte Arbeit, aber wir werden bereit sein.<\/span><\/strong><\/em><\/p><\/blockquote>\n<p><span style=\"color: #000000;\">Denn auch wenn die Haie aktuell nur Sechster in der Tabelle sind, untersch\u00e4tzen wird man K\u00f6ln definitiv nicht. Daf\u00fcr haben sie zu viele Spieler im Kader, die einfach gutes Eishockey spielen k\u00f6nnen. Und sie haben mit Uwe Krupp einen Trainer an der Bande, welcher sehr erfahren ist und wei\u00df, was man tun muss, um Spiele zu gewinnen. Gerade die Offensivpower der Haie kann zu einer Gefahr werden, weshalb die Eisb\u00e4ren kein Risiko eingehen wollen. Kris Foucault mit seinen Erwartungen an morgen Abend:<\/span><\/p>\n<blockquote><p><em><strong><span style=\"color: #ff0000;\">Sie haben viel Offensivpower, weshalb wir kein Risiko eingehen wollen. Wir haben gezeigt, dass wir 60 Minuten durchspielen k\u00f6nnen und wenn wir das machen, unserem System treu bleiben und einfach spielen, werden wir erfolgreich sein. Wenn wir uns an das halten, sehe ich kein Problem.<\/span><\/strong><\/em><\/p><\/blockquote>\n<p><span style=\"color: #000000;\">In den letzten beiden Spielen ist es den Eisb\u00e4ren endlich wieder gelungen, \u00fcber 60 Minuten durchzuspielen. Prompt gewann man beide Spiele und kehrte somit zur\u00fcck in die Erfolgsspur. Was aber auch daran lag, dass man defensiv wieder zu seiner Form gefunden hat. Und die starke Defensive wird auch morgen der Schl\u00fcssel zum Sieg sein, so sieht es jedenfalls Lukas Reichel:<\/span><\/p>\n<blockquote><p><em><strong><span style=\"color: #ff0000;\">Wir m\u00fcssen defensiv wieder so stark spielen, wie in den letzten Spielen. Offensiv machen wir eigentlich eh immer unsere Tore oder meistens. K\u00f6ln hat gute Einzelspieler, das wissen wir und auf die m\u00fcssen wir achten.<\/span><\/strong><\/em><\/p><\/blockquote>\n<p><span style=\"color: #000000;\">Lukas Reichel spricht es an, vorne machen die Eisb\u00e4ren eh fast immer ihre Tore. Mit 84 Toren stellen die Berliner den zweitbesten Angriff der PENNY DEL nach Red Bull M\u00fcnchen (88 Tore). Wichtig in den Spielen ist von daher auch immer das erste Tor, denn das gibt die Richtung in einem Spiel vor. Und das ist laut Kris Foucault vor allem ausw\u00e4rts besonders wichtig:<\/span><\/p>\n<blockquote><p><strong><em><span style=\"color: #ff0000;\">Ja, besonders ausw\u00e4rts das erste Tor zu schie\u00dfen, ist wichtig. Nat\u00fcrlich k\u00f6nnen wir momentan keinen Fansupport dadurch mitnehmen, aber das erste Tor kann den Ton f\u00fcr das restliche Spiel angeben.<\/span><\/em><\/strong><\/p><\/blockquote>\n<p><span style=\"color: #000000;\">Die Nummer 98 der Eisb\u00e4ren kennt sich da ja bestens mit aus, ist er doch &#8222;Mister 1:0&#8220; beim Hauptstadtclub. Aktuell spielt er zusammen mit Matt White und Zach Boychuk in einer Reihe. Die drei Spieler harmonieren sehr gut und haben alleine gegen Iserlohn im letzten Spiel satte 15 Torsch\u00fcsse zusammen kreiert. Wieviel Spa\u00df macht es Foucault denn \u00fcberhaupt, ein Teil dieser Angriffsreihe zu sein?<\/span><\/p>\n<blockquote><p><em><strong><span style=\"color: #ff0000;\">Es macht sehr viel Spa\u00df. Alle beiden k\u00f6nnen gut schie\u00dfen, ich ebenso. Wir pushen uns gegenseitig und haben eine gute Chemie. Es macht Spa\u00df in der Offensivzone zu spielen und das wissen wir. Das ist definitiv die Rolle, die wir spielen wollen und das werden wir weitermachen.<\/span><\/strong><\/em><\/p><\/blockquote>\n<p><span style=\"color: #000000;\">Foucault selbst hat auch schon 12-mal eingenetzt. Aber das allein ist nicht der Grundstein des Erfolges der Eisb\u00e4ren Berlin in dieser Saison. Der liegt neben der Offensive vor allem auch in der sehr stabilen Defensive, was auch Kris Foucault so sieht:<\/span><\/p>\n<blockquote><p><strong><span style=\"color: #ff0000;\"><em>Ja, wenn wir den Puck haben, ist es schwer f\u00fcr das andere Team, Tore zu schie\u00dfen. Und wenn wir Fehler machen oder in Konter laufen, haben wir Mathias Niederberger oder Tobias Ancicka, die beide gro\u00dfe Rettungsaktionen zum richtigen Zeitpunkt machen. Von der Defensive bis zur Offensive sind wir gut mit dem Puck und umso mehr wir den Puck haben, umso weniger Chancen haben die Gegner, Tore zu schie\u00dfen.<\/em><\/span><\/strong><\/p><\/blockquote>\n<p><span style=\"color: #000000;\">Starke Defensive, starke Offensive, doch was gef\u00e4llt Trainer Serge Aubin am Spiel seiner Mannschaft aktuell am besten?<\/span><\/p>\n<blockquote><p><em><strong><span style=\"color: #ff0000;\">Unserer Einsatz f\u00fcr jeden Teil des Spiels gef\u00e4llt mir am meisten momentan. \u00dcberzahl und Unterzahl sind gut, wir sind mit und ohne Puck sehr aufmerksam. In den letzten Spielen haben wir das sehr gut gemacht. Die Idee ist, den aktuellen Trend fortzuf\u00fchren. Logischerweise m\u00fcssen wir Tore schie\u00dfen und eine gute Offensive haben, aber defensiv werden Spiele gewonnen. Bei F\u00fcnf-gegen-F\u00fcnf sind wir ein schwerer Gegner und das soll weiterhin so bleiben.<\/span><\/strong><\/em><\/p><\/blockquote>\n<p><span style=\"color: #000000;\">Die gute Offensive haben die Berliner, das wurde mehrfach angesprochen. Doch was macht die Eisb\u00e4ren in diesem Jahr so torgef\u00e4hrlich? Lukas Reichel hat die Erkl\u00e4rung daf\u00fcr parat:<\/span><\/p>\n<blockquote><p><em><strong><span style=\"color: #ff0000;\">Ich w\u00fcrde sagen, dass bei uns alle vier Reihen Tore schie\u00dfen k\u00f6nnen. Auch gegen Bremerhaven, da hat man gesehen, die dritte, vierte Reihe hat auch mal ein Tor geschossen. Jede Reihe spielt zur Zeit richtig gut und es reicht f\u00fcr den Trainer, er kann alle Reihen spielen lassen.<\/span><\/strong><\/em><\/p><\/blockquote>\n<p><span style=\"color: #000000;\">Damit sind die Hauptst\u00e4dter f\u00fcr den Gegner sehr schwer auszurechnen. Denn wenn die Paradereihe Noebels-Reichel-Pf\u00f6derl nicht trifft, dann schie\u00dft eben die Reihe White-Boychuk-Foucault die Tore. Und wenn auch die mal nicht treffen, dann sind die Youngsters um Sebastian Streu, Nino Kinder und Haakon H\u00e4nelt zur Stelle, so wie im letzten Ausw\u00e4rtsspiel in Bremerhaven, als Streu sein erstes Saisontor erzielte, Nino Kinder sein erster Scorerpunkt in der DEL gelang und Haakon H\u00e4nelt sein erstes Profitor erzielte.<\/span><br \/>\n<span style=\"color: #000000;\">Gegner K\u00f6ln hat aber drei Eisb\u00e4ren-Kenner im Team, spielten doch Justin Pogge, Landon Ferraro und James Sheppard noch an der Spree. Ist es eigentlich komisch, gegen die alten Weggef\u00e4hrten zu spielen? Das wurde Lukas Reichel vor dem Spiel in der Domstadt gefragt:<\/span><\/p>\n<blockquote><p><span style=\"color: #ff0000;\"><strong><em>Nein, komisch nicht. Aber man kennt sich gegenseitig, man wei\u00df, was das f\u00fcr ein Spieler ist. Sheppy ist einfach stark an der Scheibe, kann gut die Scheibe abdecken. Landon kann seine Rolle richtig gut nutzen und wei\u00df, was er zu tun hat. Ja, und Pogge ist wie ein sechster Verteidiger manchmal, der spielt richtig gut die Scheibe. Also wir wissen, was die St\u00e4rken von denen sind und die wissen unsere St\u00e4rken. Ja, aber komisch ist da eigentlich nichts dran.<\/em><\/strong><\/span><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Morgen Abend spielen die Eisb\u00e4ren Berlin letztmals in der diesj\u00e4hrigen Hauptrunde der PENNY DEL bei den K\u00f6lner Haien (Bully: 18:30 Uhr). Alle bisherigen drei Duelle gingen an die Hauptst\u00e4dter. W\u00e4hrend die Eisb\u00e4ren souver\u00e4n an der Tabellenspitze der Gruppe Nord thronen, k\u00e4mpfen die Domst\u00e4dter als Tabellensechster noch um die Teilnahme an&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/eisbaerlin.de\/blog\/2021\/03\/09\/besonders-auswaerts-ist-es-wichtig-das-erste-tor-zu-erzielen\/\">Continue reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[166,4,8,352,137,19,429,425,427,387,7,5],"tags":[],"class_list":["post-9380","post","type-post","status-publish","format-standard","hentry","category-aktuelles-aus-der-liga","category-del","category-ebb","category-eisbaeren-berlin","category-eisbaren-news","category-kec","category-kris-foucault","category-lukas-reichel","category-saison-2020-2021","category-serge-aubin","category-spieltagsvorschau","category-wbn"],"_links":{"self":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/9380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/comments?post=9380"}],"version-history":[{"count":2,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/9380\/revisions"}],"predecessor-version":[{"id":9382,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/9380\/revisions\/9382"}],"wp:attachment":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/media?parent=9380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/categories?post=9380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/tags?post=9380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}