{"id":8914,"date":"2020-01-30T22:14:10","date_gmt":"2020-01-30T21:14:10","guid":{"rendered":"https:\/\/eisbaerlin.de\/blog\/?p=8914"},"modified":"2020-01-30T22:14:10","modified_gmt":"2020-01-30T21:14:10","slug":"bayrisches-wochenende-die-eisbaeren-sind-heiss-auf-die-beiden-wegweisenden-heimspiele-gegen-straubing-und-ingolstadt","status":"publish","type":"post","link":"https:\/\/eisbaerlin.de\/blog\/2020\/01\/30\/bayrisches-wochenende-die-eisbaeren-sind-heiss-auf-die-beiden-wegweisenden-heimspiele-gegen-straubing-und-ingolstadt\/","title":{"rendered":"Bayrisches Wochenende: Die Eisb\u00e4ren sind hei\u00df auf die beiden wegweisenden Heimspiele gegen Straubing und Ingolstadt"},"content":{"rendered":"<p><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-12\" src=\"https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/2012\/09\/125px-Logo_ERC_Ingolstadt_svg.png\" alt=\"\" width=\"100\" height=\"114\" \/>Die Deutsche Eishockey Liga (DEL) biegt auf die Zielgerade der diesj\u00e4hrigen Hauptrunde ein und somit kommen wir dem H\u00f6hepunkt einer jeden Saison immer n\u00e4her. Die Playoffs stehen vor der T\u00fcr und f\u00fcr die Eisb\u00e4ren Berlin bietet das kommende Wochenende gleich einmal die beste Gelegenheitdaf\u00fcr, f\u00fcr den Saisonh\u00f6hepunkt zu proben. Denn man trifft am Freitagabend (19:30 Uhr) auf die Straubing Tigers, ihres Zeichens Tabellendritter mit sieben Punkten Vorsprung auf die Eisb\u00e4ren, und am Sonntagnachmittag auf den ERC Ingolstadt (17:00 Uhr), ihres Zeichens Tabellensechster mit acht Punkten R\u00fcckstand auf die Berliner. F\u00fcr die Hauptst\u00e4dter also zwei enorm wichtige Heimspiele, in denen man wichtige Punkte im Kampf um Heimrecht im Viertelfinale einfahren, mit Straubing aber sogar im Falle eines Sieges dem Dritten n\u00e4her kommen kann. Mit zwei Siegen w\u00fcrde man dem Saisonziel n\u00e4her kommen, mit zwei Niederlagen aber w\u00fcrde dieses noch einmal in gro\u00dfe Gefahr geraten.<\/span><\/p>\n<p><span style=\"color: #000000;\">Aber die Eisb\u00e4ren wissen um die gro\u00dfe Bedeutung der Spiele am Freitag und Sonntag, wollen beide Spiele siegreich gestalten und damit nach dem Sieg in M\u00fcnchen ein weiteres Zeichen in Richtung Playoffs setzen. Dennoch blicken die Berliner laut Trainer Serge Aubin nicht auf die Tabelle (<em>Quelle: Medieninformation der Eisb\u00e4ren Berlin vom 30.01.2020<\/em>):<\/span><\/p>\n<blockquote><p><em><span style=\"color: #ff0000;\"><b>Ich wei\u00df, ich wiederhole mich hier, aber die Tabelle interessiert uns derzeit nicht wirklich. Wir<\/b> <\/span><\/em><em><span style=\"color: #ff0000;\"><b>konzentrieren uns komplett auf uns und unser Spiel. Morgen ist nat\u00fcrlich eine gute Gelegenheit, um uns gegen ein Team, das \u00fcber uns steht zu beweisen. Wir konzentrieren uns derzeit vor allem darauf, Eishockeyspiele zu gewinnen.<\/b><\/span><\/em><\/p><\/blockquote>\n<p><span style=\"color: #000000;\">Verteidiger Frank H\u00f6rdler \u00e4u\u00dferte sich nach dem letzten Heimspiel gegen Schwenningen auch \u00fcber den morgigen Gegner Straubing und da merkte man schon, wie gro\u00df der Respekt vor den Niederbayern ist:<\/span><\/p>\n<blockquote><p><em><strong><span style=\"color: #ff0000;\">Wenn man sich die Tabelle anguckt, ist jedes Spiel wichtig. Weil von unten dr\u00fccken sie und von oben sieht man so langsam ein bisschen Licht. Was wir wissen ist, dass Straubing eine unheimlich gute Mannschaft ist, das haben sie \u00fcber die ganze Saison bewiesen. Jeder kleinste Fehler wird genutzt von denen. Ich glaube, und das wissen wir auch, da m\u00fcssen wir von Anfang an da sein.<\/span><\/strong><\/em><\/p><\/blockquote>\n<p><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-15\" src=\"https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/2012\/09\/125px-Straubing_tigers_logo.jpg\" alt=\"\" width=\"108\" height=\"108\" \/>Den Respekt haben sich die Jungs von Chefcoach Tom Pokel auch redlich verdient, spielen sie doch die beste Hauptrunde ihre DEL-Geschichte. Die Niederbayern werden dieses Jahr im Viertelfinale mit dabei sein und dort k\u00f6nnten sie f\u00fcr jeden Gegner zum gro\u00dfen Stolperstein werden. Wenn man bei den Tigers \u00fcberhaupt etwas bem\u00e4ngeln muss, dann vielleicht den Fakt, dass das beste Heimteam der DEL das schlechteste Ausw\u00e4rtsteam aus den Top-6 der Tabelle sind. Von daher wollen die Niederbayern sich nat\u00fcrlich Heimrecht im Viertelfinale sichern. Aufpassen m\u00fcssen die Eisb\u00e4ren vor allem auf das kongeniale Sturm-Duo Michael Connolly (35 Punkte) und Jeremy Williams (32 Punkte) aufpassen.<\/span><br \/>\n<span style=\"color: #000000;\">Es ist das letzte Aufeinandertreffen beider Mannschaften in der diesj\u00e4hrigen Hauptrunde, in den Playoffs k\u00f6nnten sich die Schl\u00e4ger beider Teams aber erneut kreuzen. Bisher spricht die Bilanz f\u00fcr Berlin, die sich mit 5:2 auf heimischen Eis und 2:1 am Pulverturm durch setzten. Das erste Spiel in Straubing ging mit 3:5 verloren. In Berlin haben die Tigers vier der letzten f\u00fcnf Spiele verloren und warten seit 14 Spielen auf einen Dreier in der Hauptstadt.<\/span><br \/>\n<span style=\"color: #000000;\">Mit einem Heimsieg k\u00f6nnten die Eisb\u00e4ren den R\u00fcckstand auf Straubing auf vier Z\u00e4hler verk\u00fcrzen, bei einer Niederlage w\u00e4chst der R\u00fcckstand aber auf zehn Punkte an.<\/span><\/p>\n<p><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-286\" src=\"https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/125px-Logo_ERC_Ingolstadt_svg.png\" alt=\"\" width=\"99\" height=\"119\" \/>So ein Sechs-Punkte-Spiel wird auch das zweite Heimspiel an diesem Wochenende gegen den ERC Ingolstadt, welcher sich noch Chancen auf Heimrecht im Viertelfinale ausrechnet. Bei acht Punkten bedarf es aber eines Sieges in der Hauptstadt, um diese Chance am Leben zu halten. Die Schanzer spielen so ein bisschen eine Achterbahn-Saison, so richtig einzusch\u00e4tzen ist die Mannschaft von Coach Doug Shedden nicht. Mal sind sie richtig stark, dann aber im n\u00e4chsten Spiel wieder schlecht. In den letzten drei Spielen zeigten die Panther wieder ihr schlechtes Gesicht, verloren dreimal in Folge mit 1:4.<\/span><br \/>\n<span style=\"color: #000000;\">Aber in Berlin f\u00fchlten sie sich zuletzt pudelwohl, gewannen dreimal in Folge in der Hauptstadt. So auch das erste Duell in dieser Saison, was mit 5:4 n.P. an den ERCI ging. In Ingolstadt gewannen die Eisb\u00e4ren mit 4:2 und 4:1.<\/span><\/p>\n<p><span style=\"color: #000000;\">Bei den zuletzt dreimal in Folge siegreichen Eisb\u00e4ren wird sich im Vergleich zum Schwenningen-Spiel nichts \u00e4ndern. Hei\u00dft also auch, dass weiterhin Vincent Hessler, Florian Busch, Louis-Marc Aubry und Sean Backman fehlen werden.<\/span><\/p>\n<p><strong><em><span style=\"color: #0000ff;\">Der Eisb\u00e4ren-Kader f\u00fcr das Heimspiel gegen die Straubing Tigers am 31.01.2020 um 19:30 Uhr:<\/span><\/em><\/strong><\/p>\n<p><strong><em><span style=\"color: #0000ff;\">Tor:<\/span><\/em><\/strong><\/p>\n<p><em><span style=\"color: #008000;\">Sebastian Dahm, Justin Pogge<\/span><\/em><\/p>\n<p><em><strong><span style=\"color: #0000ff;\">Abwehr:<\/span><\/strong><\/em><\/p>\n<p><span style=\"color: #008000;\"><em>Kai Wissmann, Frank H\u00f6rdler, Jonas M\u00fcller, John Ramage, Ryan McKiernan, Florian Kettemer<\/em><\/span><\/p>\n<p><strong><em><span style=\"color: #0000ff;\">Angriff:<\/span><\/em><\/strong><\/p>\n<p><em><span style=\"color: #008000;\">Austin Ortega, Pierre-C\u00e9dric Labrie, Andr\u00e9 Rankel, Landon Ferraro, Maxim Lapierre, Lukas Reichel, Sebastian Streu, Fabian Dietz, James Sheppard, Constantin Braun, Mark Olver, Marcel Noebels, Leo Pf\u00f6derl<\/span><\/em><\/p>\n<p><em><strong><span style=\"color: #0000ff;\">F\u00fcrs DNL-Team im Einsatz:<\/span><\/strong><\/em><\/p>\n<p><em><span style=\"color: #ff0000;\">Eric Steffen<\/span><\/em><\/p>\n<p><em><strong><span style=\"color: #0000ff;\">In Wei\u00dfwasser:<\/span><\/strong><\/em><\/p>\n<p><em><span style=\"color: #ff0000;\">Marvin C\u00fcpper, Eric Mik, Thomas Reichel<\/span><\/em><\/p>\n<p><em><strong><span style=\"color: #0000ff;\">Nicht zur Verf\u00fcgung:<\/span><\/strong><\/em><\/p>\n<p><em><span style=\"color: #ff0000;\">Vincent Hessler (Hand), Louis-Marc Aubry (Knie), Sean Backman, Florian Busch<\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Deutsche Eishockey Liga (DEL) biegt auf die Zielgerade der diesj\u00e4hrigen Hauptrunde ein und somit kommen wir dem H\u00f6hepunkt einer jeden Saison immer n\u00e4her. Die Playoffs stehen vor der T\u00fcr und f\u00fcr die Eisb\u00e4ren Berlin bietet das kommende Wochenende gleich einmal die beste Gelegenheitdaf\u00fcr, f\u00fcr den Saisonh\u00f6hepunkt zu proben. Denn&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/eisbaerlin.de\/blog\/2020\/01\/30\/bayrisches-wochenende-die-eisbaeren-sind-heiss-auf-die-beiden-wegweisenden-heimspiele-gegen-straubing-und-ingolstadt\/\">Continue reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[166,4,8,352,137,13,287,386,7,9,5],"tags":[],"class_list":["post-8914","post","type-post","status-publish","format-standard","hentry","category-aktuelles-aus-der-liga","category-del","category-ebb","category-eisbaeren-berlin","category-eisbaren-news","category-ing","category-mercedes-benz-arena","category-saison-2019-2020","category-spieltagsvorschau","category-str","category-wbn"],"_links":{"self":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/8914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/comments?post=8914"}],"version-history":[{"count":1,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/8914\/revisions"}],"predecessor-version":[{"id":8915,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/8914\/revisions\/8915"}],"wp:attachment":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/media?parent=8914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/categories?post=8914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/tags?post=8914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}