{"id":6206,"date":"2016-03-03T20:00:49","date_gmt":"2016-03-03T19:00:49","guid":{"rendered":"http:\/\/eisbaerlin.de\/blog\/?p=6206"},"modified":"2016-03-03T20:00:49","modified_gmt":"2016-03-03T19:00:49","slug":"uwe-krupp-das-war-kein-gutes-spiel-von-uns","status":"publish","type":"post","link":"https:\/\/eisbaerlin.de\/blog\/2016\/03\/03\/uwe-krupp-das-war-kein-gutes-spiel-von-uns\/","title":{"rendered":"Uwe Krupp: &#8222;Das war kein gutes Spiel von uns&#8220;"},"content":{"rendered":"<p><span style=\"color: #000080;\"><em><strong>Frank H\u00f6rdler (Verteidiger Eisb\u00e4ren Berlin):<\/strong><\/em><\/span><\/p>\n<blockquote><p><span style=\"color: #ff0000;\"><strong><em>Es ist entt\u00e4uschend, vor allem, wenn man 2:0 f\u00fchrt. Wir hatten davor auch ein Spiel, wo wir gef\u00fchrt haben und das dann aber noch aus der Hand gegeben haben. Daran sieht man, dass man vom ersten bis zum letzten Platz immer top da sein muss, sonst geht es schnell in die andere Richtung.\u00a0<\/em><\/strong><\/span><\/p><\/blockquote>\n<p><span style=\"color: #000080;\"><em><strong>Milan Jurcina (Verteidiger Eisb\u00e4ren Berlin):<\/strong><\/em><\/span><\/p>\n<blockquote><p><em><strong><span style=\"color: #ff0000;\">Nach so einem Spiel kann es keinem gut gehen. Wir h\u00e4tten nach dem ersten Drittel eigentlich schon 3:0, 4:0 f\u00fchren m\u00fcssen, da haben wir richtig gut gespielt. \u00a0Aber das hat leider nicht geklappt und dann ist Schwenningen immer besser ins Spiel gekommen, hat das 2:2 im Powerplay erzielt und dann das 3:2 so ein bisschen gl\u00fccklich.\u00a0<\/span><\/strong><\/em><\/p><\/blockquote>\n<p><span style=\"color: #000080;\"><em><strong>Uwe Krupp (Trainer Eisb\u00e4ren Berlin):<\/strong><\/em><\/span><\/p>\n<blockquote><p><span style=\"color: #ff0000;\"><em><strong>Das war ein cleveres Spiel von Schwenningen, die haben in den letzten 40 Minuten viele gute Sachen gemacht. Und wir haben nicht gut gespielt. Das war kein gutes Spiel von uns. Wir werden am Freitag besser spielen.\u00a0<\/strong><\/em><\/span><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frank H\u00f6rdler (Verteidiger Eisb\u00e4ren Berlin): Es ist entt\u00e4uschend, vor allem, wenn man 2:0 f\u00fchrt. Wir hatten davor auch ein Spiel, wo wir gef\u00fchrt haben und das dann aber noch aus der Hand gegeben haben. Daran sieht man, dass man vom ersten bis zum letzten Platz immer top da sein muss,&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/eisbaerlin.de\/blog\/2016\/03\/03\/uwe-krupp-das-war-kein-gutes-spiel-von-uns\/\">Continue reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[166,4,8,137,289,24,56,5],"tags":[],"class_list":["post-6206","post","type-post","status-publish","format-standard","hentry","category-aktuelles-aus-der-liga","category-del","category-ebb","category-eisbaren-news","category-saison-20152016","category-stimmen-der-trainer","category-stimmen-zum-spiel","category-wbn"],"_links":{"self":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/6206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/comments?post=6206"}],"version-history":[{"count":1,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/6206\/revisions"}],"predecessor-version":[{"id":6207,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/6206\/revisions\/6207"}],"wp:attachment":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/media?parent=6206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/categories?post=6206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/tags?post=6206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}