{"id":578,"date":"2012-10-02T20:54:04","date_gmt":"2012-10-02T18:54:04","guid":{"rendered":"http:\/\/eisbaerlin.de\/blog\/?p=578"},"modified":"2012-10-02T20:54:04","modified_gmt":"2012-10-02T18:54:04","slug":"hamburg-freezers-verpflichten-nhl-spieler","status":"publish","type":"post","link":"https:\/\/eisbaerlin.de\/blog\/2012\/10\/02\/hamburg-freezers-verpflichten-nhl-spieler\/","title":{"rendered":"Hamburg Freezers verpflichten NHL-Spieler"},"content":{"rendered":"<p><a href=\"http:\/\/eisbaerlin.de\/blog\/2012\/09\/22\/del-saison-20122013-3-spieltag-mannheim-nicht-zu-stoppen-nurnberg-gewinnt-spitzenspiel\/200px-hamburg-freezers_svg\/\" rel=\"attachment wp-att-18\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-18\" title=\"200px-Hamburg-freezers_svg\" src=\"http:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/2012\/09\/200px-Hamburg-freezers_svg.png\" alt=\"\" width=\"160\" height=\"62\" \/><\/a>Nun wechselt auch der erste ausl\u00e4ndische Lockout-Spieler in die Deutsche Eishockey Liga (DEL). Die Hamburg Freezers verpflichteten <a title=\"Jamie Benn nach Hamburg\" href=\"http:\/\/www.eishockeynews.de\/aktuell\/artikel\/2012\/10\/02\/hamburg-holt-nhl-stuermer-benn-aus-dallas-seidenberg-in-mannheim-eingetroffen.html\">heute<\/a> St\u00fcrmer Jamie Benn. Der 23-j\u00e4hrige kommt von den Dallas Stars, f\u00fcr die er in 222 Spielen 70 Tore erzielte und 90 weitere Treffer vorbereitete. Benn ist nach Christian Ehrhoff (Krefeld), Marcel Goc und Dennis Seidenberg (beide Mannheim) bereits der vierte NHL-Spieler,der w\u00e4hrend des Lockouts in der DEL spielen wird.<\/p>\n<p>Jamie Benn soll, wenn alles klappt, bereits am Freitag im Heimspiel gegen die Adler Mannheim sein DEL-Deb\u00fct feiern. Sportdirektor St\u00e9phane Richer \u00e4u\u00dferte sich zu dem Transfer wie folgt:<\/p>\n<blockquote><p>Wir sind froh, dass es uns gelungen ist, mit Jamie Benn einen absoluten Top-Spieler aus der NHL zu verpflichten. Er verf\u00fcgt \u00fcber alle offensiven F\u00e4higkeiten, ist sehr torgef\u00e4hrlich, technisch und k\u00f6rperlich stark. Dar\u00fcber hinaus ist er mit 23 Jahren noch jung und entwicklungsf\u00e4hig. Jamie freut sich sehr auf seine Aufgabe in Hamburg und ist froh, dass die Spielpause nun f\u00fcr ihn beendet ist. Wenn die Lizensierung normal verl\u00e4uft, k\u00f6nnen wir ihn direkt am Freitag beim Heimspiel gegen Mannheim einsetzen.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Nun wechselt auch der erste ausl\u00e4ndische Lockout-Spieler in die Deutsche Eishockey Liga (DEL). Die Hamburg Freezers verpflichteten heute St\u00fcrmer Jamie Benn. Der 23-j\u00e4hrige kommt von den Dallas Stars, f\u00fcr die er in 222 Spielen 70 Tore erzielte und 90 weitere Treffer vorbereitete. Benn ist nach Christian Ehrhoff (Krefeld), Marcel Goc&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/eisbaerlin.de\/blog\/2012\/10\/02\/hamburg-freezers-verpflichten-nhl-spieler\/\">Continue reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14,6,62,5],"tags":[],"class_list":["post-578","post","type-post","status-publish","format-standard","hentry","category-del","category-hhf","category-saison-20122013","category-transfers","category-wbn"],"_links":{"self":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/comments?post=578"}],"version-history":[{"count":2,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/578\/revisions"}],"predecessor-version":[{"id":580,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/578\/revisions\/580"}],"wp:attachment":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/media?parent=578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/categories?post=578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/tags?post=578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}