{"id":4679,"date":"2014-10-17T22:19:35","date_gmt":"2014-10-17T20:19:35","guid":{"rendered":"http:\/\/eisbaerlin.de\/blog\/?p=4679"},"modified":"2014-10-17T22:19:35","modified_gmt":"2014-10-17T20:19:35","slug":"nach-02-rueckstand-eisbaeren-gewinnen-mit-32-n-v-in-koeln-julian-talbot-erzielt-das-game-winning-goal","status":"publish","type":"post","link":"https:\/\/eisbaerlin.de\/blog\/2014\/10\/17\/nach-02-rueckstand-eisbaeren-gewinnen-mit-32-n-v-in-koeln-julian-talbot-erzielt-das-game-winning-goal\/","title":{"rendered":"Nach 0:2-R\u00fcckstand: Eisb\u00e4ren gewinnen mit 3:2 n.V. in K\u00f6ln &#8211; Julian Talbot erzielt das Game-Winning-Goal"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-16\" src=\"http:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/2012\/09\/130px-Koelner-haie-logo_svg.png\" alt=\"130px-Koelner-haie-logo_svg\" width=\"130\" height=\"116\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-12\" src=\"http:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/2012\/09\/125px-Logo_ERC_Ingolstadt_svg.png\" alt=\"125px-Logo_ERC_Ingolstadt_svg\" width=\"100\" height=\"114\" \/><\/p>\n<p>Die Eisb\u00e4ren Berlin sind zur\u00fcck in der Erfolgsspur. Nach zuvor drei Niederlagen in Folge (CHL und DEL) gewannen die Hauptst\u00e4dter am Freitagabend vor 10.057 Zuschauern in der Lanxess-Arena bei den K\u00f6lner Haien mit 3:2 n.V. (0:2, 0:0, 2:0\/ 1:0). Die Eisb\u00e4ren drehten dabei einen 0:2-R\u00fcckstand noch in einen Sieg um, welcher am Ende dank des gro\u00dfen Aufwandes der Berliner absolut verdient war.<\/p>\n<p>Die Eisb\u00e4ren Berlin hatten gleich zu Spielbeginn die Chance zur fr\u00fchen F\u00fchrung. K\u00f6ln kassierte nach drei Spielminuten eine Strafe wegen zu vieler Spieler auf dem Eis, die Eisb\u00e4ren also in \u00dcberzahl. Statistisch gesehen sind die Berliner da die beste Mannschaft in der DEL. Und das Powerplay sah auch sehr gut aus. Die Eisb\u00e4ren fanden schnell in die Powerplay-Formation und lie\u00dfen die Scheibe sehr gut laufen. Julian Talbot (2) und Marcel Noebels kamen dann auch zu guten Chancen, doch ein Tor gelang den G\u00e4sten in diesem \u00dcberzahlspiel nicht. Dagegen h\u00e4tten beinahe die Domst\u00e4dter das 1:0 in Unterzahl erzielt. Marcel Ohmann mit einem klasse Pass auf Ex-Eisb\u00e4r Alex Wei\u00df, welcher frei vor Petri Vehanen zum Schuss kam. Doch der finnische Goalie mit einer klasse Parade.<br \/>\nNach sieben Spielminuten dann auch die Haie mit ihem ersten Powerplay (Barry Tallackson sa\u00df wegen \u00fcbertriebener H\u00e4rte auf der Strafbank). Und auch das Powerplay der K\u00f6lner sah sehr gut aus. Alex Wei\u00df und Philip Gogulla pr\u00fcften Petri Vehanen, doch der behielt in beiden Duellen jeweils die Oberhand.<br \/>\nDie Eisb\u00e4ren waren dann nur kurze Zeit wieder vollz\u00e4hlig, denn Kapit\u00e4n Andr\u00e9 Rankel kassierte in der 9. Spielminute eine Strafzeit wegen Stockschlags. Und diesmal konnten die Domst\u00e4dter das \u00dcberzahlspiel nutzen. Jamie Johnson tankte sich bis zur Grundlinie durch, passte den Puck dann r\u00fcber an den langen Pfosten zu Mike Iggulden, der Petri Vehanen keine Chance lie\u00df und zum 1:0 einschoss (10.).<br \/>\nDie Eisb\u00e4ren wirkten jedoch nicht geschockt, suchten sofort den Weg in die Offensive. Auch K\u00f6ln versuchte sich immer wieder in der Offensive zu zeigen. Richtig gef\u00e4hrlich wurde es aber erst wieder, als es eine Strafe gab. Diesmal traf es K\u00f6ln und die Eisb\u00e4ren hatten wieder einen Mann mehr auf dem Eis. Erneut kamen die Hauptst\u00e4dter gut in die Formation und lie\u00dfen die Scheibe gut laufen, auch zum Abschluss kamen die Berliner, jedoch standen die Haie in der Defensive sehr gut und konnten die Sch\u00fcsse immer wieder blocken.<br \/>\nDrei Minuten vor der ersten Drittelpause K\u00f6ln dann mit dem zweiten Treffer an diesem Abend. Erneut war es Jamie Johnson, der den Puck klasse vor das Tor passte. Chris Minard lauerte im Slot und schoss den Puck rechts oben ins Eck &#8211; 2:0 (17.).<br \/>\nMit diesem Spielstand ging es es dann in die erste Drittelpause. Die Eisb\u00e4ren keineswegs mit einer schlechten Partie, sie kamen auch zu guten Torchancen. Doch K\u00f6ln zeigte sich im Abschluss eiskalt und f\u00fchrte somit nicht unverdient mit 2:0.<!--more--><\/p>\n<p>Das zweite Drittel begannen die Eisb\u00e4ren in Unterzahl. Neuzugang Marcel Noebels kassierte in der Schlussminute noch eine Zwei-Minuten-Strafe wegen Beinstellens. Als Barry Tallackson dann wenig sp\u00e4ter auch noch vom Eis musste, waren die Haie pl\u00f6tzlich zwei Mann mehr auf dem Eis &#8211; und das f\u00fcr ganze 24 Sekunden. Doch viel hatte der KEC davon nicht, denn Philipp Gogulla musste in der 22. Spielminute auch auf die Strafbank, weshalb es bei 4-gegen-4 weiter ging und am Ende die Eisb\u00e4ren noch 37 Sekunden Powerplay hatten. Doch zum Torerfolg reichte es f\u00fcr die Eisb\u00e4ren nicht.<br \/>\nDanach entwickelte sich eine eher zerfahrene Partie, in der es vor allem viele Zweik\u00e4mpfe gab aber wenig Torraumszenen.<br \/>\nEs waren dann die Eisb\u00e4ren, die wieder f\u00fcr spielerische Akzente sorgen konnten. Petr Pohl fuhr einen 2-auf-1-Konter mit Marcel Noebels, zog dann aber alleine ab, Danny Aus den Birken im K\u00f6lner Tor war aber zur Stelle. Nur wenige Sekunden nach dieser Chance setzte Pohl Antti Miettinen klasse in Szene, der Finne scheiterte jedoch bei seinem Versuch aus dem Slot heraus an Aus den Birken. Fast im Gegenzug dann die K\u00f6lner mit einer Chance, Mirko L\u00fcdemann wurde jedoch von T.J. Mulock zu Fall gebracht und die beiden Schiedsrichter Aicher und Schukies entschieden auf Penalty f\u00fcr K\u00f6ln. Die Haie-Legende Mirko L\u00fcdemann scheiterte beim Penalty jedoch an Petri Vehanen.<br \/>\nDie letzten zehn Minuten des Mitteldrittels waren dann ein dauerhaftes Powerplay der Eisb\u00e4ren. Die Mannen von Chefcoach Jeff Tomlinosn machten richtig viel Druck, K\u00f6ln konnte sich kaum befreien. Petr Pohl versuchte sich per Bauerntrick, scheiterte jedoch an Aus den Birken. In \u00dcberzahl kamen dann Frank H\u00f6rdler, Antti Miettinen und Andr\u00e9 Rankel zu richtig guten Chancen, doch am Haie-Keeper war nach wie vor kein vorbeikommen.<br \/>\nK\u00f6ln kam erst in den letzten Minuten des zweiten Drittels noch einmal zu guten Chancen, doch Charlie Stephens und Chris Minard scheiterten an Petri Vehanen im Eisb\u00e4ren-Tor.<br \/>\nKurz vor der zweiten Drittelpause hatte dann Youngster Sven Ziegler noch einmal eine gro\u00dfe Chance, aber auch er scheiterte an Danny Aus den Birken. Somit blieb es beim 2:0 nach 40 Minuten f\u00fcr K\u00f6ln. Eine mittlerweile schmeichelhafte F\u00fchrung f\u00fcr die Domst\u00e4dter, die sich vor allem in den letzten zehn Minuten einem Dauerdruck der Eisb\u00e4ren ausgesetzt sahen. Nur die Eisb\u00e4ren konnten aus ihren Chancen (24 Torsch\u00fcsse im Mitteldrittel) nichts machen, K\u00f6ln zeigte sich im ersten Drittel im Abschluss effektiv. Das machte bisher den Unterschied in dieser Partie aus. Aber noch blieben den Berlinern ja 20 Minuten Zeit.<\/p>\n<p>Im Schlussdrittel ging es zun\u00e4chst hin und her. Beide Mannschaften mit Zug zum Tor, jedoch noch ohne Gl\u00fcck im Abschluss. Pech\u00a0hatte Chris Minard in der 45. Spielminute, als er mit seinem Schuss nur die Latte traf. Praktisch im Gegenzug konnten sich die Eisb\u00e4ren endlich f\u00fcr ihren gro\u00dfen Aufwand belohnen. Casey Borer mit einem lockeren Handgelenkschuss, Danny Aus den Birken lie\u00df nur prallen und Petr Pohl schaltete im Gew\u00fchl vor dem Tor am Schnellsten &#8211; 2:1 (46.). Der f\u00fcnfte Saisontreffer des Tschechen.<br \/>\nVier Minuten sp\u00e4ter h\u00e4tte Henry Haase beinahe den Ausgleich erzielt, doch sein Schuss ging nur an das Lattenkreuz. Zwei Minuten sp\u00e4ter dann K\u00f6ln mal wieder gef\u00e4hrlich vor dem Berliner Tor. Aber Nick Latta und Evan Rankin konnten den Puck nicht im Berliner Tor unterbringen.<br \/>\nDie Eisb\u00e4ren danach weiterhin bem\u00fcht, mit viel Druck auf das K\u00f6lner Tor. K\u00f6ln lauerte auf Fehler der Eisb\u00e4ren, doch die machten keinen. Im Gegenteil. Zwei Minuten vor dem Ende der regul\u00e4ren Spielzeit gelang den Eisb\u00e4ren der mittlerweile hoch verdiente Ausgleich. Constantin Braun mit dem Pass zu Frank H\u00f6rdler, welcher von der blauen Linie einfach mal abzog. Mit Erfolg, H\u00f6rdler sein Schlagschuss schlug hinter Aus den Birken ein und so stand es in der Lanxess-Arena durch das erste Saisontor von Frank H\u00f6rdler 2:2 (58.). Es ging also in die Verl\u00e4ngerung.<\/p>\n<p>Und dort kr\u00f6nten die Eisb\u00e4ren dann ihre Aufholjagd und machten den Sieg perfekt. Constantin Braun fuhr ins K\u00f6lner Drittel, kam zum Abschluss und auch zum Nachuss. Braun kam erneut an den Puck und fuhr rum ums Tor, passte dann vor das Tor zu Julian Talbot, welcher den Puck zum 3:2 ins K\u00f6lner Tor schoss &#8211; 3:2 (63.). Der vierte Saisontreffer von Julian Talbot bescherte den Eisb\u00e4ren am Ende den mehr als verdienten Zusatzpunkt.<\/p>\n<p>Ein am Ende mehr als verdienter Eisb\u00e4ren-Sieg. Im ersten Drittel zeigten die Eisb\u00e4ren schon gute Ans\u00e4tze und hatten auch gute Chancen, aber die Haie waren vor dem Tor einfach effektiver als die Berliner und so f\u00fchrte der KEC nach 20 Minuten mit 2:0. Sp\u00e4testens ab Mitte des zweiten Drittels \u00fcbernahmen die Eisb\u00e4ren das Spiel-Kommando und setzten die Hausherren dauerhaft unter Druck. Gerade im Mitteldrittel feuerten die Eisb\u00e4ren 24-mal auf das K\u00f6lner Tor, aber Danny Aus den Birken war erst im Schlussdrittel zu \u00fcberwinden. Am Ende war dann auch der K\u00f6lner Goalie irgendwann geschlagen, zu gro\u00df war der Druck der Eisb\u00e4ren, die am Ende 53 Sch\u00fcsse auf das K\u00f6lner Tor abgaben. Eine starke k\u00e4mpferische Leistung der Eisb\u00e4ren, welche nach dem 0:2 gro\u00dfe Moral zeigten und nie aufgaben. Letzten Sonntag hatten die Eisb\u00e4ren ein \u00e4hnliches Spiel in Wolfsburg gezeigt, dort wurden sie f\u00fcr ihren Aufwand aber nicht belohnt. Heute war es anders, zum Gl\u00fcck f\u00fcr die Eisb\u00e4ren.<\/p>\n<p>Eisb\u00e4ren-Chefcoach Jeff Tomlinson war nach dem Spiel froh \u00fcber die Sieg, trauerte aber auch dem einen verlorenen Punkt nach:<\/p>\n<blockquote><p><span style=\"color: #ff0000;\"><em><strong>Ich\u00a0finde, wir haben einen Punkt liegen lassen. Nach dem 0:2\u00a0haben wir uns gut zur\u00fcck gek\u00e4mpft. In der zweiten Drittelpause habe ich den Jungs gesagt, sie sollen einfach so weiter spielen, dann f\u00e4llt auch irgendwann das Tor. Wir nehmen die zwei Punkte gerne mit. Wir haben gut gespielt, wir haben immer noch daran geglaubt, dass wir das Spiel noch drehen k\u00f6nnen. Hut ab vor unseren Jungs, wie sie gek\u00e4mpft haben.<\/strong><\/em><\/span><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Die Eisb\u00e4ren Berlin sind zur\u00fcck in der Erfolgsspur. Nach zuvor drei Niederlagen in Folge (CHL und DEL) gewannen die Hauptst\u00e4dter am Freitagabend vor 10.057 Zuschauern in der Lanxess-Arena bei den K\u00f6lner Haien mit 3:2 n.V. (0:2, 0:0, 2:0\/ 1:0). Die Eisb\u00e4ren drehten dabei einen 0:2-R\u00fcckstand noch in einen Sieg um,&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/eisbaerlin.de\/blog\/2014\/10\/17\/nach-02-rueckstand-eisbaeren-gewinnen-mit-32-n-v-in-koeln-julian-talbot-erzielt-das-game-winning-goal\/\">Continue reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[166,4,8,137,230,19,259,25,24,56,5],"tags":[],"class_list":["post-4679","post","type-post","status-publish","format-standard","hentry","category-aktuelles-aus-der-liga","category-del","category-ebb","category-eisbaren-news","category-jeff-tomlinson","category-kec","category-saison-20142015","category-spieltagsberichte","category-stimmen-der-trainer","category-stimmen-zum-spiel","category-wbn"],"_links":{"self":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/4679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/comments?post=4679"}],"version-history":[{"count":1,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/4679\/revisions"}],"predecessor-version":[{"id":4684,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/4679\/revisions\/4684"}],"wp:attachment":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/media?parent=4679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/categories?post=4679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/tags?post=4679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}