{"id":11042,"date":"2023-07-05T19:57:44","date_gmt":"2023-07-05T17:57:44","guid":{"rendered":"https:\/\/eisbaerlin.de\/blog\/?p=11042"},"modified":"2023-07-05T19:58:55","modified_gmt":"2023-07-05T17:58:55","slug":"goalie-nikita-quapp","status":"publish","type":"post","link":"https:\/\/eisbaerlin.de\/blog\/2023\/07\/05\/goalie-nikita-quapp\/","title":{"rendered":"Goalie: Nikita Quapp"},"content":{"rendered":"<p><span style=\"color: #000000;\">In diesem Blog-Artikel werden wir uns genauer mit der Karriere und den Erfolgen des jungen<\/span><br \/>\n<span style=\"color: #000000;\">Torh\u00fcters Nikita Quapp befassen. Viel Spa\u00df beim Lesen!<\/span><\/p>\n<div id=\"attachment_11043\" style=\"width: 930px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-11043\" class=\"size-large wp-image-11043\" src=\"https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-MAN-EBB23-014k-1024x682.jpg\" alt=\"\" width=\"920\" height=\"613\" srcset=\"https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-MAN-EBB23-014k-1024x682.jpg 1024w, https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-MAN-EBB23-014k-300x200.jpg 300w, https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-MAN-EBB23-014k-768x512.jpg 768w, https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-MAN-EBB23-014k-1536x1023.jpg 1536w, https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-MAN-EBB23-014k-2048x1365.jpg 2048w, https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-MAN-EBB23-014k-525x350.jpg 525w, https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-MAN-EBB23-014k-150x100.jpg 150w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><p id=\"caption-attachment-11043\" class=\"wp-caption-text\"><span style=\"color: #0000ff;\"><em>Foto: City-Press GmbH<\/em><\/span><\/p><\/div>\n<p><span style=\"color: #000000;\">Nikita Quapp ist ein talentierter junger Goalie und kam 2022-23 zu den Eisb\u00e4ren Berlin. Er <\/span><span style=\"color: #000000;\">wurde am 25.01.2003 in Ravensburg geboren und spielte 2015-16 auch im Jugendteam der <\/span><span style=\"color: #000000;\">Ravensburger. Von 2016-2020 war er in \u00d6sterreich in der RB-Akademie unterwegs.<\/span><br \/>\n<span style=\"color: #000000;\">Unter anderem nahm er an der U17 als auch an der U18 teil und spielte insgesamt sieben Spiele. <\/span><span style=\"color: #000000;\">2020-21 wurde er f\u00fcr die WJC-18 nominiert und absolvierte zwei Spiele. F\u00fcr die WJC-20 wurde <\/span><span style=\"color: #000000;\">er ebenfalls nominiert und durfte auch hier wieder zwei Spiele f\u00fcr die U20 bestreiten.<\/span><\/p>\n<p><span style=\"color: #000000;\">Im Jahr 2021-22 gab Quapp sein Deb\u00fct in der DEL bei den Krefeld Pinguinen. Er durfte in <\/span><span style=\"color: #000000;\">dieser Saison elf Spiele absolvieren, in denen am Ende zwei Siege und sechs Niederlagen zu Buche standen.<\/span><\/p>\n<p><span style=\"color: #000000;\">Letzte Saison war er f\u00fcr die Eisb\u00e4ren und f\u00fcr die Lausitzer F\u00fcchse im Einsatz. In der DEL <\/span><span style=\"color: #000000;\">reichte es nur f\u00fcr ein Spiel mit einem GAA von 3,11 und einer SV% von 88,9%. Bei den F\u00fcchsen <\/span><span style=\"color: #000000;\">stand er 12 Spiele im Tor und hatte dort einen GAA von 2,67 und eine SV% von 91,7%, <\/span><span style=\"color: #000000;\">daraus resultieren sechs Siege und sechs Niederlagen.<\/span><br \/>\n<span style=\"color: #000000;\">In den Playoffs durfte er f\u00fcnf Spiele bestreiten in denen er einen GAA von 2.81 und eine SV% von <\/span><span style=\"color: #000000;\">90,7% erreichte.<\/span><br \/>\n<span style=\"color: #000000;\">Es standen die WJC-20 an, wo Quapp vier Spiele machte und leider nur ein Sieg und drei <\/span><span style=\"color: #000000;\">Niederlagen heraussprangen. Quapp hat schon einige Stationen hinter sich und viel <\/span><span style=\"color: #000000;\">Erfahrung im internationalen Bereich gesammelt.<\/span><\/p>\n<p><span style=\"color: #000000;\">Sein Talent blieb nicht unentdeckt, Quapp wurde im NHL-Draft 2021 an Stelle 187 in Runde 6 <\/span><span style=\"color: #000000;\">von den Carolina Hurricanes gedraftet.<\/span><\/p>\n<div id=\"attachment_11044\" style=\"width: 930px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-11044\" class=\"size-large wp-image-11044\" src=\"https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-WOB-KEV22-027k-1024x683.jpg\" alt=\"\" width=\"920\" height=\"614\" srcset=\"https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-WOB-KEV22-027k-1024x683.jpg 1024w, https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-WOB-KEV22-027k-300x200.jpg 300w, https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-WOB-KEV22-027k-768x512.jpg 768w, https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-WOB-KEV22-027k-1536x1024.jpg 1536w, https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-WOB-KEV22-027k-2048x1365.jpg 2048w, https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-WOB-KEV22-027k-525x350.jpg 525w, https:\/\/eisbaerlin.de\/blog\/wp-content\/uploads\/cp-d1-WOB-KEV22-027k-150x100.jpg 150w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><p id=\"caption-attachment-11044\" class=\"wp-caption-text\"><span style=\"color: #0000ff;\"><em>Foto: Moritz Eden\/City-Press GmbH<\/em><\/span><\/p><\/div>\n<p><span style=\"color: #000000;\">Als er damals noch f\u00fcr die Krefeld Pinguine aufgelaufen ist, hatte er der Mannschaft oft den <\/span><span style=\"color: #000000;\">R\u00fccken frei gehalten, indem er herausragende Saves gezeigt hat. Aber wie hei\u00dft es so sch\u00f6n? <\/span><span style=\"color: #000000;\">Machst du die Tore vorne nicht, bekommst du sie hinten irgendwann rein. (<em>hier 1\u20ac ins <\/em><\/span><span style=\"color: #000000;\"><em>Phrasenschwein<\/em>) Der 20-j\u00e4hrige Torh\u00fcter wird uns hoffentlich noch viel Freude bereiten.<\/span><\/p>\n<p><span style=\"color: #000000;\">Viele werden Ihn jetzt mit Stettmer vergleichen und sagen: Ja der hat ja eine viel bessere <\/span><span style=\"color: #000000;\">Statistik. Wirklich zum Vergleichen reicht das aber nicht, da m\u00fcssen einige Spiele absolviert <\/span><span style=\"color: #000000;\">werden, um vern\u00fcnftige Schl\u00fcsse daraus ziehen zu k\u00f6nnen. Ich denke jedoch, das <\/span><span style=\"color: #000000;\">Stettmer z.B. eine deutlich stabilere Defensive vor sich hatte, die gut gearbeitet hat um ihm <\/span><span style=\"color: #000000;\">seinen Job so \u201e<em>einfach wie m\u00f6glich<\/em>\u201c zu gestalten. Es wird super interessant werden, wie <\/span><span style=\"color: #000000;\">Quapp sich mit der neuen Defensive beweist und sich zeigt. Zudem sind beide Goalies\u00a0 jung und <\/span><span style=\"color: #000000;\">wollen den Fans sicherlich etwas beweisen. <\/span><\/p>\n<p><span style=\"color: #000000;\">Quapp wird weiterhin hart an sich arbeiten um in <\/span><span style=\"color: #000000;\">der Saison 2023-24 mehr als nur ein Spiel in der DEL zu spielen. Eine kleine Wundert\u00fcte die wir <\/span><span style=\"color: #000000;\">im Back-up Bereich haben. Es kribbelt langsam schon in den Fingern, die Jungs mal wieder in <\/span><span style=\"color: #000000;\">Aktion zu erleben, oder was meint ihr?<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In diesem Blog-Artikel werden wir uns genauer mit der Karriere und den Erfolgen des jungen Torh\u00fcters Nikita Quapp befassen. Viel Spa\u00df beim Lesen! Nikita Quapp ist ein talentierter junger Goalie und kam 2022-23 zu den Eisb\u00e4ren Berlin. Er wurde am 25.01.2003 in Ravensburg geboren und spielte 2015-16 auch im Jugendteam&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/eisbaerlin.de\/blog\/2023\/07\/05\/goalie-nikita-quapp\/\">Continue reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[503,4,8,352,137,211,505,478,231,486,510],"tags":[],"class_list":["post-11042","post","type-post","status-publish","format-standard","hentry","category-city-press","category-del","category-ebb","category-eisbaeren-berlin","category-eisbaren-news","category-impressionen","category-jule","category-nikita-quapp","category-portrait","category-spielervorstellung","category-youngsters"],"_links":{"self":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/11042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/comments?post=11042"}],"version-history":[{"count":4,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/11042\/revisions"}],"predecessor-version":[{"id":11051,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts\/11042\/revisions\/11051"}],"wp:attachment":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/media?parent=11042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/categories?post=11042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/tags?post=11042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}