{"id":475,"count":1,"description":"","link":"https:\/\/eisbaerlin.de\/blog\/category\/saisonfazit-2021-2022\/","name":"Saisonfazit 2021\/2022","slug":"saisonfazit-2021-2022","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/categories\/475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/eisbaerlin.de\/blog\/wp-json\/wp\/v2\/posts?categories=475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}